{"id":1847,"date":"2025-08-20T07:53:44","date_gmt":"2025-08-20T07:53:44","guid":{"rendered":"https:\/\/q81vpbtwbc.preview.infomaniak.website\/persoenliches-gespraech\/"},"modified":"2026-05-07T15:08:35","modified_gmt":"2026-05-07T15:08:35","slug":"persoenliches-gespraech","status":"publish","type":"page","link":"https:\/\/sawi.com\/de\/persoenliches-gespraech\/","title":{"rendered":"Pers\u00f6nliches Gespr\u00e4ch"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1847\" class=\"elementor elementor-1847 elementor-64\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-682e055 e-flex e-con-boxed e-con e-parent\" data-id=\"682e055\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bc444c3 e-con-full e-flex e-con e-child\" data-id=\"bc444c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-25717fe e-con-full e-flex e-con e-child\" data-id=\"25717fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f0de22 elementor-widget elementor-widget-heading\" data-id=\"3f0de22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pers\u00f6nliches Gespr\u00e4ch<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cee317a elementor-widget elementor-widget-heading\" data-id=\"cee317a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">15 Minuten, um herauszufinden, wie Sie Ihre Karriere am besten voranbringen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b9b099 elementor-widget elementor-widget-text-editor\" data-id=\"3b9b099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">In einem 15-min\u00fctigen pers\u00f6nlichen Gespr\u00e4ch mit unserem Studien- &amp; Kursberater analysieren Sie Ihre aktuelle Situation und erfahren, wie Sie Ihre Karriere gezielt weiterentwickeln k\u00f6nnen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e143a3e e-con-full e-flex e-con e-child\" data-id=\"e143a3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22d3486 elementor-widget elementor-widget-heading\" data-id=\"22d3486\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nach diesem Gespr\u00e4ch nehmen sie folgendes mit:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85c60a8 sw-custom-li sw-black elementor-widget elementor-widget-text-editor\" data-id=\"85c60a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Eine fundierte Einsch\u00e4tzung Ihrer aktuellen Situation durch einen Experten<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Mehr Klarheit \u00fcber Ihre beruflichen und pers\u00f6nlichen Ziele<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Konkrete Optionen, die zu Ihnen passen \u2013 und wie Sie diese optimal nutzen<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Einen klaren Fahrplan, um Ihre Karriere erfolgreich voranzubringen<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-075f6fa e-con-full e-flex e-con e-child\" data-id=\"075f6fa\" data-element_type=\"container\" data-e-type=\"container\" id=\"calendrier\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4b46a6 elementor-widget elementor-widget-html\" data-id=\"d4b46a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!-- Calendly inline widget begin -->\r\n<div class=\"calendly-inline-widget\" data-url=\"https:\/\/calendly.com\/h-schildknecht-sawi\"><\/div>\r\n<script type=\"text\/javascript\" src=\"https:\/\/assets.calendly.com\/assets\/external\/widget.js\" async=\"\"><\/script>\r\n<!-- Calendly inline widget end -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pers\u00f6nliches Gespr\u00e4ch 15 Minuten, um herauszufinden, wie Sie Ihre Karriere am besten voranbringen In einem 15-min\u00fctigen pers\u00f6nlichen Gespr\u00e4ch mit unserem Studien- &amp; Kursberater analysieren Sie Ihre aktuelle Situation und erfahren, wie Sie Ihre Karriere gezielt weiterentwickeln k\u00f6nnen. Nach diesem Gespr\u00e4ch nehmen sie folgendes mit: Eine fundierte Einsch\u00e4tzung Ihrer aktuellen Situation durch einen Experten Mehr Klarheit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1847","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sawi.com\/de\/wp-json\/wp\/v2\/pages\/1847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sawi.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sawi.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sawi.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sawi.com\/de\/wp-json\/wp\/v2\/comments?post=1847"}],"version-history":[{"count":15,"href":"https:\/\/sawi.com\/de\/wp-json\/wp\/v2\/pages\/1847\/revisions"}],"predecessor-version":[{"id":22922,"href":"https:\/\/sawi.com\/de\/wp-json\/wp\/v2\/pages\/1847\/revisions\/22922"}],"wp:attachment":[{"href":"https:\/\/sawi.com\/de\/wp-json\/wp\/v2\/media?parent=1847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}